{"id":7025,"date":"2010-01-01T00:01:52","date_gmt":"2009-12-31T23:01:52","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=7025"},"modified":"2009-12-31T22:37:27","modified_gmt":"2009-12-31T21:37:27","slug":"diabsite-wunscht-ihnen-ein-gutes-neues-jahr-2","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2010\/01\/01\/diabsite-wunscht-ihnen-ein-gutes-neues-jahr-2\/","title":{"rendered":"DiabSite w\u00fcnscht Ihnen ein gutes neues Jahr"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2010\/silvester-2010.jpg\" width=\"150\" height=\"66\" alt=\"Frohes neues Jahr\" \/> Sie, liebe Besucherinnen und Besucher, haben 2009 mit weit \u00fcber 2,2&nbsp;Millionen Besuchen auf der DiabSite und 120.000&nbsp;Besuchen im <a href=\"https:\/\/www.diabetes-radio.de\/\" target=\"_blank\" class=\"radio\" title=\"neues Fenster\">DiabSite Diabetes-Radio<\/a> gezeigt, wie viel Ihnen unsere Arbeit bedeutet. Ihr Interesse ist uns Lob und Ansporn zugleich. Deshalb haben wir auch f\u00fcr 2010 wieder viele Pl\u00e4ne geschmiedet und noch mehr Ideen entwickelt. Lassen Sie sich \u00fcberraschen. Heute danken wir Ihnen herzlich f\u00fcr das in uns gesetzte Vertrauen und Ihr gro\u00dfes Interesse am Diabetes-Portal DiabSite. Wir freuen uns auf Ihre Besuche und w\u00fcnschen Ihnen f\u00fcr 2010 viel Gesundheit, Gl\u00fcck und Erfolg!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie, liebe Besucherinnen und Besucher, haben 2009 mit weit \u00fcber 2,2&nbsp;Millionen Besuchen auf der DiabSite und 120.000&nbsp;Besuchen im DiabSite Diabetes-Radio gezeigt, wie viel Ihnen unsere Arbeit bedeutet. Ihr Interesse ist uns Lob und Ansporn zugleich. Deshalb haben wir auch f\u00fcr 2010 wieder viele Pl\u00e4ne geschmiedet und noch mehr Ideen entwickelt. Lassen Sie sich \u00fcberraschen. Heute [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/7025"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=7025"}],"version-history":[{"count":3,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/7025\/revisions"}],"predecessor-version":[{"id":7028,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/7025\/revisions\/7028"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=7025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=7025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=7025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}