{"id":66,"date":"2005-05-18T16:32:35","date_gmt":"2005-05-18T14:32:35","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/2005\/05\/18\/66\/"},"modified":"2006-12-28T16:22:16","modified_gmt":"2006-12-28T15:22:16","slug":"aufarbeitung-der-informationsflut-2005","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2005\/05\/18\/aufarbeitung-der-informationsflut-2005\/","title":{"rendered":"Aufarbeitung der Informationsflut vom Diabetes-Kongress"},"content":{"rendered":"<p>Noch immer arbeite ich fieberhaft an der Aufbereitung der zahlreichen Diabetes-Informationen, die im Rahmen des Diabetes-Kongresses in Berlin auf mich eingest\u00fcrmt sind. So fand ich heute zum Beispiel eine interessante Meldung zur kontinuierlichen Blutzuckermessung. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2005\/050503c.html\" target=\"_blank\">Nachricht lesen<\/a><br \/>\nAber auch das Thema &#8222;Diabetes und Depression&#8220; ist f\u00fcr zahlreiche Menschen mit Diabetes offensichtlich von gro\u00dfer Bedeutung. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2005\/050503d.html\" target=\"_blank\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noch immer arbeite ich fieberhaft an der Aufbereitung der zahlreichen Diabetes-Informationen, die im Rahmen des Diabetes-Kongresses in Berlin auf mich eingest\u00fcrmt sind. So fand ich heute zum Beispiel eine interessante Meldung zur kontinuierlichen Blutzuckermessung. Nachricht lesen Aber auch das Thema &#8222;Diabetes und Depression&#8220; ist f\u00fcr zahlreiche Menschen mit Diabetes offensichtlich von gro\u00dfer Bedeutung. Nachricht lesen<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/66"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=66"}],"version-history":[{"count":0,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/66\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=66"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=66"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=66"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}