{"id":62663,"date":"2026-05-10T08:47:10","date_gmt":"2026-05-10T06:47:10","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=62663"},"modified":"2026-05-10T08:49:20","modified_gmt":"2026-05-10T06:49:20","slug":"diabetes-portal-diabsite-zum-muttertag-3","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2026\/05\/10\/diabetes-portal-diabsite-zum-muttertag-3\/","title":{"rendered":"Diabetes-Portal DiabSite zum Muttertag"},"content":{"rendered":"<h4>Das gesamte DiabSite-Team w\u00fcnscht alles Gute zum Muttertag!<\/h4>\n<p><i>Zum Vergr\u00f6\u00dfern bitte auf die Webkater klicken.<\/i><\/p>\n<p><a href=\"https:\/\/www.diabsite.de\/_img\/grafics\/muttertag-webkater-gr.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diabsite.de\/_img\/grafics\/muttertag-webkater.jpg\" class=\"alignright\" width=\"200\" height=\"118\" alt=\"Webkater des Diabetes-Portals DiabSite.\"><\/a> Sie haben keine Pralinen gekauft; Blumen sind im Garten sowieso sch\u00f6ner als in der Vase; und eine <a href=\"https:\/\/www.diabsite.de\\ernaehrung\\rezepte\\muttertags-herzen.html\" target=\"_blank\" class=\"ds\" title=\"zum Rezept (neues Fenster\" rel=\"noopener\">Muttertagstorte<\/a> haben die Sie auch nicht gebacken? Was k\u00f6nnen Kinder und V\u00e4ter heute noch tun, um der Frau und Mutter zu danken? Zum Beispiel mit viel Liebe das Fr\u00fchst\u00fcck vorbereiteten oder aus Papier ein Herz ausschneiden und darauf notieren: &#8222;waschen, putzen, kochen, organisieren, zuh\u00f6ren&#8220;, also Dinge, wof\u00fcr sie der Frau des Hauses danken. Allen M\u00fcttern gilt Dank f\u00fcr die unz\u00e4hligen kleinen T\u00e4tigkeiten, die sie erledigen, und die im Alltag oft \u00fcbersehen werden. Auch wir von der DiabSite sind &#8222;M\u00fctter&#8220;. Unsere &#8222;Kinder&#8220; sind die Webkater Banti und Charly, um die wir uns t\u00e4glich liebevoll k\u00fcmmern. Seit knapp sechs Jahren bringen sie uns oft zum Lachen, zeigen uns schnurrend wie Entspannung geht und stellen so manchen Bl\u00f6dsinn an. Zum heutigen Muttertag genie\u00dfen sie wie damals die Sonne. Mehr \u00fcber die beiden felltragenden Mitglieder der DiabSite-Redaktion finden Sie in unserem Diabetes-Weblog, wenn Sie nach <a href=\"\/diabetes-weblog\/index.php?s=Webkater\">&#8222;Webkater&#8220;<\/a> suchen. Allen M\u00fcttern und Katzenm\u00fcttern w\u00fcnscht das DiabSite-Team einen sch\u00f6nen Muttertag!<\/p>\n<p><i>Sie, liebe Leser\/innen, sind herzlich eingeladen, diesen Beitrag zu kommentieren. Dazu bitte auf die \u00dcberschrift klicken und das Formular ausf\u00fcllen.<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das gesamte DiabSite-Team w\u00fcnscht alles Gute zum Muttertag! Zum Vergr\u00f6\u00dfern bitte auf die Webkater klicken. Sie haben keine Pralinen gekauft; Blumen sind im Garten sowieso sch\u00f6ner als in der Vase; und eine Muttertagstorte haben die Sie auch nicht gebacken? Was k\u00f6nnen Kinder und V\u00e4ter heute noch tun, um der Frau und Mutter zu danken? Zum [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6143,896,11672,787,15,13659,13658,294],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/62663"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=62663"}],"version-history":[{"count":5,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/62663\/revisions"}],"predecessor-version":[{"id":62671,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/62663\/revisions\/62671"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=62663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=62663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=62663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}