{"id":60763,"date":"2024-11-26T18:52:16","date_gmt":"2024-11-26T17:52:16","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=60763"},"modified":"2024-11-26T18:52:16","modified_gmt":"2024-11-26T17:52:16","slug":"adipositas-therapie-2","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2024\/11\/26\/adipositas-therapie-2\/","title":{"rendered":"Adipositas-Therapie"},"content":{"rendered":"<h3>Zusatzbezeichnung Ern\u00e4hrungsmedizin sichert qualifizierte Versorgung<\/h3>\n<h4>Gemeinsame Stellungnahme von DGEM, BDEM und DAEM<\/h4>\n<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/241126.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/241126.jpg\" class=\"alignright\" width=\"200\" height=\"182\" alt=\"Adipositas im Fokus\"><\/a> Adipositas betrifft rund ein Viertel der erwachsenen Bev\u00f6lkerung in Deutschland und f\u00fchrt h\u00e4ufig zu schwerwiegenden Folgeerkrankungen wie Diabetes Typ&nbsp;2 oder Herz-Kreislauf-Problemen. Eine effektive Behandlung setzt einen multimodalen Therapieansatz voraus, der in jedem Fall eine qualifizierte ern\u00e4hrungsmedizinische Betreuung umfasst. Mit der Zusatz-Weiterbildung &#8222;Ern\u00e4hrungsmedizin&#8220; steht \u00c4rztinnen und \u00c4rzten eine umfassende, evidenzbasierte Ausbildung zur Behandlung von Menschen mit Adipositas zur Verf\u00fcgung. Diese Zusatzbezeichnung deckt alle relevanten Inhalte ab. Zus\u00e4tzliche Fortbildungen wie etwa zum &#8222;Adiposiologe&#8220; oder &#8222;Adipologe&#8220; k\u00f6nnen einen Stellenwert in der allgemeinen \u00e4rztlichen Fortbildung haben, seien aber f\u00fcr Ern\u00e4hrungsmedizinerinnen und Ern\u00e4hrungsmediziner weder inhaltlich noch formal erforderlich, betonen die Deutsche Gesellschaft f\u00fcr Ern\u00e4hrungsmedizin&nbsp;e.V.&nbsp;(DGEM), der Berufsverband Deutscher Ern\u00e4hrungsmedizinerinnen und Ern\u00e4hrungsmediziner&nbsp;e.V.&nbsp;(BDEM) und die Deutsche Akademie f\u00fcr Ern\u00e4hrungsmedizin&nbsp;e.V.&nbsp;(DAEM) in ihrer aktuellen Stellungnahme. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/241126.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zusatzbezeichnung Ern\u00e4hrungsmedizin sichert qualifizierte Versorgung Gemeinsame Stellungnahme von DGEM, BDEM und DAEM Adipositas betrifft rund ein Viertel der erwachsenen Bev\u00f6lkerung in Deutschland und f\u00fchrt h\u00e4ufig zu schwerwiegenden Folgeerkrankungen wie Diabetes Typ&nbsp;2 oder Herz-Kreislauf-Problemen. Eine effektive Behandlung setzt einen multimodalen Therapieansatz voraus, der in jedem Fall eine qualifizierte ern\u00e4hrungsmedizinische Betreuung umfasst. Mit der Zusatz-Weiterbildung &#8222;Ern\u00e4hrungsmedizin&#8220; steht [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[6786,1621,12196,12913],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/60763"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=60763"}],"version-history":[{"count":1,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/60763\/revisions"}],"predecessor-version":[{"id":60765,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/60763\/revisions\/60765"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=60763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=60763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=60763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}