{"id":60004,"date":"2024-04-18T13:11:04","date_gmt":"2024-04-18T11:11:04","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=60004"},"modified":"2024-04-18T22:25:46","modified_gmt":"2024-04-18T20:25:46","slug":"ende-des-aezq-quo-vadis-versorgungsqualitaet","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2024\/04\/18\/ende-des-aezq-quo-vadis-versorgungsqualitaet\/","title":{"rendered":"Ende des \u00c4ZQ&nbsp;&#8211; Quo vadis Versorgungsqualit\u00e4t?"},"content":{"rendered":"<h4>Deutsche Diabetes Gesellschaft fordert eine rasche L\u00f6sung f\u00fcr zentrale qualit\u00e4tssichernde Aufgaben in der Patientenversorgung<\/h4>\n<p>Das \u00c4rztliche Zentrum f\u00fcr Qualit\u00e4t in der Medizin&nbsp;(\u00c4ZQ) wird zum Ende dieses Jahres aufgel\u00f6st. Die Deutsche Diabetes Gesellschaft&nbsp;(DDG) hat diese \u00fcberraschende Nachricht mit gro\u00dfer Sorge aufgenommen. Ohne die Arbeit des \u00c4ZQ droht eine Verschlechterung der Patientensicherheit und der Versorgungsqualit\u00e4t in Deutschland. Denn eine wichtige Aufgabe dieses Zentrums ist es, die Versorgungsqualit\u00e4t und das Versorgungsmanagement im Gesundheitswesen zu \u00fcberwachen und zu unterst\u00fctzen. Dazu z\u00e4hlt auch die Erstellung der Nationalen VersorgungsLeitlinien&nbsp;(NVL), die Basis sind f\u00fcr viele strukturierte Behandlungsprogramme&nbsp;(<a href=\"\/infos\/lexikon\/index.html#dmp\" class=\"lex\">DMP<\/a>). Die DDG fordert daher, die Aufgaben des \u00c4ZQ rasch an eine kompetente Stelle zu geben, die staatlich unabh\u00e4ngig agieren muss. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240418.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche Diabetes Gesellschaft fordert eine rasche L\u00f6sung f\u00fcr zentrale qualit\u00e4tssichernde Aufgaben in der Patientenversorgung Das \u00c4rztliche Zentrum f\u00fcr Qualit\u00e4t in der Medizin&nbsp;(\u00c4ZQ) wird zum Ende dieses Jahres aufgel\u00f6st. Die Deutsche Diabetes Gesellschaft&nbsp;(DDG) hat diese \u00fcberraschende Nachricht mit gro\u00dfer Sorge aufgenommen. Ohne die Arbeit des \u00c4ZQ droht eine Verschlechterung der Patientensicherheit und der Versorgungsqualit\u00e4t in Deutschland. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12593,483,1308,735,12594],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/60004"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=60004"}],"version-history":[{"count":1,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/60004\/revisions"}],"predecessor-version":[{"id":60005,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/60004\/revisions\/60005"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=60004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=60004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=60004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}