{"id":59992,"date":"2024-04-09T14:49:32","date_gmt":"2024-04-09T12:49:32","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=59992"},"modified":"2024-04-09T21:56:33","modified_gmt":"2024-04-09T19:56:33","slug":"fuer-dexcom-rtcgm-systeme-nun-noch-breitere-kostenuebernahme-bei-typ-2-diabetes","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2024\/04\/09\/fuer-dexcom-rtcgm-systeme-nun-noch-breitere-kostenuebernahme-bei-typ-2-diabetes\/","title":{"rendered":"F\u00fcr Dexcom rtCGM-Systeme nun noch breitere Kosten\u00fcbernahme bei Typ-2-Diabetes"},"content":{"rendered":"<h4>Dexcom und KKH weiten zum 01.04.2024 ihre Partnerschaft aus<\/h4>\n<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240409.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240409.jpg\" class=\"alignright\" width=\"150\" height=\"103\" alt=\"Friseurin mit Dexcom G7-Sensor.\"><\/a> Dexcom setzt sich als weltweiter Hersteller smarter Glukosesensoren daf\u00fcr ein, den Zugang zu dieser digitalen Diabetestechnologie m\u00f6glichst vielen Patientinnen und Patienten zu erm\u00f6glichen. Mit einem seiner Partner ebnet das Unternehmen nun einer Kosten\u00fcbernahme auch abseits der intensivierten Insulintherapie&nbsp;(ICT) den Weg: Die KKH&nbsp;Kaufm\u00e4nnische Krankenkasse erm\u00f6glicht mit einer neuen Satzungsleistung zum 01.04.2024 ihren Versicherten mit Diabetes mellitus Typ&nbsp;2 und einer Behandlung aus der sog. BOT-Gruppe (basal unterst\u00fctzte orale Therapie) die Versorgung mit einem rtCGM-System f\u00fcr bis zu 12&nbsp;Monate. Ziel ist es, durch Coachingeffekte das Verst\u00e4ndnis der Zusammenh\u00e4nge zwischen Bewegung, Ern\u00e4hrung, und Insulin mit dem Glukosewert zu f\u00f6rdern und so durch eine bessere Stoffwechseleinstellung langfristig Folgeerkrankungen zu reduzieren. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240409.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dexcom und KKH weiten zum 01.04.2024 ihre Partnerschaft aus Dexcom setzt sich als weltweiter Hersteller smarter Glukosesensoren daf\u00fcr ein, den Zugang zu dieser digitalen Diabetestechnologie m\u00f6glichst vielen Patientinnen und Patienten zu erm\u00f6glichen. Mit einem seiner Partner ebnet das Unternehmen nun einer Kosten\u00fcbernahme auch abseits der intensivierten Insulintherapie&nbsp;(ICT) den Weg: Die KKH&nbsp;Kaufm\u00e4nnische Krankenkasse erm\u00f6glicht mit einer [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[6797,12578,12580,12579,12399,92],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59992"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=59992"}],"version-history":[{"count":1,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59992\/revisions"}],"predecessor-version":[{"id":59993,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59992\/revisions\/59993"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=59992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=59992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=59992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}