{"id":59980,"date":"2024-04-06T12:16:59","date_gmt":"2024-04-06T10:16:59","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=59980"},"modified":"2024-04-07T21:41:06","modified_gmt":"2024-04-07T19:41:06","slug":"weltgesundheitstag-am-7-april-2024-meine-gesundheit-mein-recht","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2024\/04\/06\/weltgesundheitstag-am-7-april-2024-meine-gesundheit-mein-recht\/","title":{"rendered":"Weltgesundheitstag am 7. April 2024: &#8222;Meine Gesundheit, mein Recht&#8220;"},"content":{"rendered":"<h4>diabetesDE fordert erneut die Umsetzung der &#8222;Nationalen Diabetesstrategie&#8220;<\/h4>\n<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240406.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240406.jpg\" class=\"alignright\" width=\"200\" height=\"209\" alt=\"Dr. Jens Kr\u00f6ger, Vorstandsvorsitzender von diabetesDE\"><\/a> Anl\u00e4sslich der Gr\u00fcndung der Weltgesundheitsorganisation&nbsp;(WHO) im Jahr&nbsp;1948 findet jedes Jahr am 7.&nbsp;April der Weltgesundheitstag statt. Das internationale Motto f\u00fcr 2024 lautet &#8222;My health, my right&#8220; beziehungsweise in Deutschland: &#8222;Meine Gesundheit, mein Recht&#8220;. Im Rahmenprogramm Gesundheitsforschung der Bundesregierung steht in Leitlinie&nbsp;I: &#8222;Der Mensch im Mittelpunkt&#8220;. F\u00fcr Menschen mit Diabetes mellitus und jene mit einem hohen Erkrankungsrisiko sei das jedoch nicht die Realit\u00e4t, mahnt die gemeinn\u00fctzige Gesundheitsorganisation diabetesDE&nbsp;\u2013 Deutsche Diabetes-Hilfe an. Mittlerweile gibt es hierzulande 8,7&nbsp;Millionen diagnostizierte Menschen mit Typ-2-Diabetes und 372000 mit Typ-1-Diabetes. Bev\u00f6lkerungsbasierte Studien gehen von 13,1&nbsp;Millionen Menschen zwischen 18 und 79&nbsp;Jahren mit einem Pr\u00e4diabetes&nbsp;(20,8&nbsp;%) aus. diabetesDE fordert, die bereits 2020 beschlossene &#8222;Nationale Diabetesstrategie&#8220; endlich umzusetzen. Dr.&nbsp;Jens Kr\u00f6ger, Vorstandsvorsitzender von diabetesDE, betont, dass Diabetes die Pandemie sei, die bleibe. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2024\/240406.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>diabetesDE fordert erneut die Umsetzung der &#8222;Nationalen Diabetesstrategie&#8220; Anl\u00e4sslich der Gr\u00fcndung der Weltgesundheitsorganisation&nbsp;(WHO) im Jahr&nbsp;1948 findet jedes Jahr am 7.&nbsp;April der Weltgesundheitstag statt. Das internationale Motto f\u00fcr 2024 lautet &#8222;My health, my right&#8220; beziehungsweise in Deutschland: &#8222;Meine Gesundheit, mein Recht&#8220;. Im Rahmenprogramm Gesundheitsforschung der Bundesregierung steht in Leitlinie&nbsp;I: &#8222;Der Mensch im Mittelpunkt&#8220;. F\u00fcr Menschen mit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[369,8806,1839],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59980"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=59980"}],"version-history":[{"count":4,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59980\/revisions"}],"predecessor-version":[{"id":59984,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59980\/revisions\/59984"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=59980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=59980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=59980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}