{"id":59005,"date":"2023-04-25T17:16:39","date_gmt":"2023-04-25T15:16:39","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=59005"},"modified":"2023-04-26T21:27:14","modified_gmt":"2023-04-26T19:27:14","slug":"amputationen-beim-diabetischen-fuss-noch-zu-haeufig","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2023\/04\/25\/amputationen-beim-diabetischen-fuss-noch-zu-haeufig\/","title":{"rendered":"Amputationen beim Diabetischen Fu\u00df noch zu h\u00e4ufig"},"content":{"rendered":"<h4>VDBD r\u00e4t, Recht auf Zweitmeinung zu nutzen<\/h4>\n<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2023\/230425.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2023\/230425.jpg\" class=\"alignright\" width=\"200\" height=\"153\" alt=\"Diabetes und F\u00fc\u00dfe\"><\/a> Seit zwei Jahren k\u00f6nnen sich Menschen mit einem diabetischen Fu\u00dfsyndrom&nbsp;(DFS) vor einer drohenden Amputation eine unabh\u00e4ngige \u00e4rztliche Zweitmeinung einholen. Doch leider wird dieser Rechtsanspruch noch zu selten von Patientinnen und Patienten genutzt, bedauert der Verband der Diabetes-Beratungs- und Schulungsberufe in Deutschland e.&nbsp;V.&nbsp;(VDBD). Er ruft Menschen mit einem DFS und drohender Amputation daher dazu auf, dieses Angebot unbedingt wahrzunehmen, um Gliedma\u00dfen zu retten und den Verlust von Lebensqualit\u00e4t und -zeit zu verhindern. \u00dcber die Homepage <a href=\"https:\/\/amputation-nein-danke.de\/\" target=\"_blank\" class=\"extern\" title=\"neues Fenster\" rel=\"noopener\">&#8222;Amputation&nbsp;&#8211; NEIN&nbsp;Danke&#8220;<\/a> finden Betroffene und Angeh\u00f6rige \u00c4rztinnen und \u00c4rzte, die individuell und qualifiziert beraten. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2023\/230425.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VDBD r\u00e4t, Recht auf Zweitmeinung zu nutzen Seit zwei Jahren k\u00f6nnen sich Menschen mit einem diabetischen Fu\u00dfsyndrom&nbsp;(DFS) vor einer drohenden Amputation eine unabh\u00e4ngige \u00e4rztliche Zweitmeinung einholen. Doch leider wird dieser Rechtsanspruch noch zu selten von Patientinnen und Patienten genutzt, bedauert der Verband der Diabetes-Beratungs- und Schulungsberufe in Deutschland e.&nbsp;V.&nbsp;(VDBD). Er ruft Menschen mit einem DFS [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[71,24,12124,9673],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59005"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=59005"}],"version-history":[{"count":1,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59005\/revisions"}],"predecessor-version":[{"id":59006,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/59005\/revisions\/59006"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=59005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=59005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=59005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}