{"id":55795,"date":"2021-04-24T14:44:11","date_gmt":"2021-04-24T12:44:11","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=55795"},"modified":"2021-04-27T20:36:05","modified_gmt":"2021-04-27T18:36:05","slug":"initiative-ir4future","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2021\/04\/24\/initiative-ir4future\/","title":{"rendered":"Initiative &#8222;IR4future&#8220;"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2021\/210424.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2021\/210424.jpg\" width=\"200\" height=\"155\" alt=\"Blutzuckermessung bei Diabetes\"\/><\/a> Wirtschaft und Wissenschaft fordern Innovationsschub in der Infrarot-Technologie: Die Infrarot-Spektroskopie erm\u00f6glicht vielversprechende Anwendungen in der medizinischen Diagnostik und Analytik&nbsp;&#8211; doch in die notwendige technologische und methodische Weiterentwicklung wird kaum noch investiert. Forschende und Industriepartner aus dem deutschsprachigen Raum rufen die Politik dazu auf, den notwendigen Innovationsrahmen zu schaffen. Andernfalls drohe man international den Anschluss zu verlieren. Der Forschungsverbund &#8222;Leibniz Gesundheitstechnologien&#8220; unterst\u00fctzt die Initiative und sieht ein gro\u00dfes Potential der Technologie in der klinischen Bildgebung und Point-of-Care-Diagnostik. Die Infrarot-Spektroskopie kann den Blutzucker messen, ohne zu stechen, anhand der Atemluft Lungen- und Nierenkrankheiten oder Diabetes schon im Fr\u00fchstadium erkennen. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2021\/210424.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\" rel=\"noopener noreferrer\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wirtschaft und Wissenschaft fordern Innovationsschub in der Infrarot-Technologie: Die Infrarot-Spektroskopie erm\u00f6glicht vielversprechende Anwendungen in der medizinischen Diagnostik und Analytik&nbsp;&#8211; doch in die notwendige technologische und methodische Weiterentwicklung wird kaum noch investiert. Forschende und Industriepartner aus dem deutschsprachigen Raum rufen die Politik dazu auf, den notwendigen Innovationsrahmen zu schaffen. Andernfalls drohe man international den Anschluss zu [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12,24,10974,10975,4244],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/55795"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=55795"}],"version-history":[{"count":2,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/55795\/revisions"}],"predecessor-version":[{"id":55814,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/55795\/revisions\/55814"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=55795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=55795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=55795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}