{"id":55718,"date":"2021-04-04T13:59:35","date_gmt":"2021-04-04T11:59:35","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=55718"},"modified":"2021-04-04T16:31:30","modified_gmt":"2021-04-04T14:31:30","slug":"ostern-erfolgreich-suchen-13","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2021\/04\/04\/ostern-erfolgreich-suchen-13\/","title":{"rendered":"Ostern erfolgreich suchen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/_img\/grafics\/ostereier-diabsite-200.jpg\" width=\"200\" height=\"175\" alt=\"bunte Ostereier\" \/> Was geh\u00f6rt f\u00fcr Sie zu Ostern? Ist es der Kirchgang, der Ostermarsch f\u00fcr den Frieden, ein gem\u00fctliches Fr\u00fchst\u00fcck, der Segen des Papstes &#8222;Urbi et Orbi&#8220; (der Stadt und dem Erdkreis) oder ein k\u00f6stliches Lammgericht? F\u00fcr die meisten Kinder jedenfalls geh\u00f6rt die Suche nach bunten Ostereiern zu den H\u00f6hepunkten des Fests. Auch Erwachsene k\u00f6nnen sich gegenseitig etwas verstecken. Das ist Diabetes-Pr\u00e4vention, die Freude bereitet. Gr\u00fcndlich hinter B\u00fcschen, im Gras oder in Blumenk\u00e4sten zu suchen, macht Spa\u00df und sorgt ganz nebenbei f\u00fcr mehr Bewegung. Ein Osterspaziergang (in Zeiten der Corona-Pandemie nur zu zweit oder innerhalb der Familie) reduziert das Diabetesrisiko noch einmal und steigert gleichzeitig die Lebensfreude.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\"  class=\"alignleft\" src=\"https:\/\/www.diabsite.de\/_img\/grafics\/osterhase-diabsite-200.jpg\" width=\"200\" height=\"160\" alt=\"Osterhase mit Ei und Pinsel\" \/> Erfolgreich suchen k\u00f6nnen Sie \u00fcbrigens auch auf dem <a href=\"https:\/\/www.diabsite.de\/index.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Diabetes-Portal DiabSite<\/a>. Das geht ganz einfach. Schauen Sie erst einmal in der Navigation oder im <a href=\"https:\/\/www.diabsite.de\/inhalt.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Inhaltsverzeichnis<\/a> der DiabSite nach Ihrem Diabetes-Thema. Weitere Ergebnisse bietet die <a href=\"https:\/\/www.diabsite.de\/suche.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Suchfunktion<\/a>. Wir haben es mit dem Wort &#8222;Ostern&#8220; probiert und sehr viele Links erhalten. Sie wollen wissen, was wir au\u00dfer &#8222;<a href=\"https:\/\/www.diabsite.de\/ernaehrung\/ostern.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Ostern dreht sich alles ums Ei<\/a>&#8220; oder &#8222;<a href=\"https:\/\/www.diabsite.de\/infos\/experten\/lesefutter\/020304-thurm.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Aktivurlaub zu Ostern<\/a>&#8220; und k\u00f6stlichen <a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/index.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Rezepten<\/a> f\u00fcr die Osterfeiertage gefunden haben? Finden Sie&#8217;s heraus. Das DiabSite-Team w\u00fcnscht Ihnen ein frohes Osterfest und viel Spa\u00df beim Suchen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was geh\u00f6rt f\u00fcr Sie zu Ostern? Ist es der Kirchgang, der Ostermarsch f\u00fcr den Frieden, ein gem\u00fctliches Fr\u00fchst\u00fcck, der Segen des Papstes &#8222;Urbi et Orbi&#8220; (der Stadt und dem Erdkreis) oder ein k\u00f6stliches Lammgericht? F\u00fcr die meisten Kinder jedenfalls geh\u00f6rt die Suche nach bunten Ostereiern zu den H\u00f6hepunkten des Fests. Auch Erwachsene k\u00f6nnen sich gegenseitig [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[494,62,3856,9331,96,109],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/55718"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=55718"}],"version-history":[{"count":4,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/55718\/revisions"}],"predecessor-version":[{"id":55722,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/55718\/revisions\/55722"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=55718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=55718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=55718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}