{"id":53165,"date":"2019-12-12T17:08:35","date_gmt":"2019-12-12T16:08:35","guid":{"rendered":"https:\/\/www.diabsite.de\/diabetes-weblog\/?p=53165"},"modified":"2019-12-12T22:19:51","modified_gmt":"2019-12-12T21:19:51","slug":"erfolgreich-abnehmen-eine-typfrage","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2019\/12\/12\/erfolgreich-abnehmen-eine-typfrage\/","title":{"rendered":"Erfolgreich abnehmen &#8211; eine Typfrage"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2019\/191212.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2019\/191212.jpg\" width=\"120\" height=\"157\" alt=\"Professor Dr. med. Monika Kellerer, Pr\u00e4sidentin der Deutschen Diabetes Gesellschaft\" \/><\/a> Auf energiereduzierte Mischkost setzen oder eher Kohlenhydrate einschr\u00e4nken? Gewichtsreduktion ist nicht nur f\u00fcr viele Diabetespatientinnen und -patienten ein wichtiges Thema. Ob sie gelingt, h\u00e4ngt stark von dem gew\u00e4hlten Ern\u00e4hrungskonzept ab. Elisabeth H\u00f6fler, Ern\u00e4hrungsexpertin der Deutschen Diabetes Gesellschaft&nbsp;(DDG), stellt zwei Erfolgsdi\u00e4ten vor. Die Stuttgarter Di\u00e4tberaterin kennt schmackhafte Rezepte und gibt praktische Tipps, wie man eine Ern\u00e4hrungsumstellung im Alltag lange gut durchh\u00e4lt. Ma\u00dfgeblich f\u00fcr den Erfolg ist auch eine individuelle und qualifizierte Ern\u00e4hrungsberatung, die verschiedene Diabetes-Typen, Behandlungsformen, soziale Aspekte sowie pers\u00f6nliche Vorlieben ber\u00fccksichtigt. Sie sollte ein wesentlicher Bestandteil der Diabetestherapie sein, fordert die&nbsp;DDG. Frau Prof. Kellerer, Pr\u00e4sidentin der Deutschen Diabetes Gesellschaft betont, dass bei der Ern\u00e4hrung nicht nur auf Kalorien und Kohlenhydrate zu achten sei, sonder insgesamt auf Fetts\u00e4urezusammensetzung, Ballaststoffe und glyk\u00e4mische Last. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2019\/191212.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n<p>Das k\u00f6nnte sie auch ineteressieren:<\/p>\n<p>&#8211; <a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/index.html\" target=\"_blank\" class=\"ds\" title=\"zu den Rezepten (neues Fenster)\">Rezepte mit N\u00e4hrwert- und BE-Angaben<\/a> &#8211; In dieser Rubrik auf dem Diabetes-Portal DiabSite gibt es auch eine Kategorie &#8222;Rezepte f\u00fcr die schlanke Linie&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf energiereduzierte Mischkost setzen oder eher Kohlenhydrate einschr\u00e4nken? Gewichtsreduktion ist nicht nur f\u00fcr viele Diabetespatientinnen und -patienten ein wichtiges Thema. Ob sie gelingt, h\u00e4ngt stark von dem gew\u00e4hlten Ern\u00e4hrungskonzept ab. Elisabeth H\u00f6fler, Ern\u00e4hrungsexpertin der Deutschen Diabetes Gesellschaft&nbsp;(DDG), stellt zwei Erfolgsdi\u00e4ten vor. Die Stuttgarter Di\u00e4tberaterin kennt schmackhafte Rezepte und gibt praktische Tipps, wie man eine Ern\u00e4hrungsumstellung [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[24,10020,7070,1130,10021],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/53165"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=53165"}],"version-history":[{"count":2,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/53165\/revisions"}],"predecessor-version":[{"id":53167,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/53165\/revisions\/53167"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=53165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=53165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=53165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}