{"id":45573,"date":"2017-12-12T20:26:08","date_gmt":"2017-12-12T19:26:08","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=45573"},"modified":"2024-12-13T10:50:47","modified_gmt":"2024-12-13T09:50:47","slug":"halbzeit-beim-adventkalender-mit-diabetes-quiz2017","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2017\/12\/12\/halbzeit-beim-adventkalender-mit-diabetes-quiz2017\/","title":{"rendered":"Halbzeit beim Adventskalender mit Diabetes-Quiz&nbsp;2017"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/aktionen\/advent\/gewinnspiel\/index.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/diabetes\/diabsite-adventskalender.jpg\" width=\"150\" height=\"107\" alt=\"DiabSite-Adventskalender\" \/><\/a> Heute um Mitternacht ist Halbzeit beim Warten auf den Weihnachtsmann. Bei Adventskalendern ist die H\u00e4lfte der 24&nbsp;T\u00fcren ge\u00f6ffnet. Beim Fu\u00dfball ginge es jetzt in die Halbzeitpause. Nicht so bei unserem Adventskalender mit Diabetes-Quiz. Da k\u00f6nnen Sie heute noch das 12.&nbsp;T\u00fcrchen \u00f6ffnen, Spa\u00df haben und gewinnen. Kluge K\u00f6pfe spielen bis zum 24.&nbsp;Dezember t\u00e4glich mit. Denn mit jeder Teilnahme steigt die Chance auf den Hauptgewinn&nbsp;&#8211; einen Amazon-Gutschein \u00fcber 100&nbsp;Euro. Auf geht&#8217;s zum traditionellen <a href=\"https:\/\/www.diabsite.de\/aktionen\/advent\/gewinnspiel\/index.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\" rel=\"noopener\">Adventskalender mit Diabetes-Quiz<\/a> auf der DiabSite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute um Mitternacht ist Halbzeit beim Warten auf den Weihnachtsmann. Bei Adventskalendern ist die H\u00e4lfte der 24&nbsp;T\u00fcren ge\u00f6ffnet. Beim Fu\u00dfball ginge es jetzt in die Halbzeitpause. Nicht so bei unserem Adventskalender mit Diabetes-Quiz. Da k\u00f6nnen Sie heute noch das 12.&nbsp;T\u00fcrchen \u00f6ffnen, Spa\u00df haben und gewinnen. Kluge K\u00f6pfe spielen bis zum 24.&nbsp;Dezember t\u00e4glich mit. Denn mit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5633,1341,1340,3007,7853,1367],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/45573"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=45573"}],"version-history":[{"count":7,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/45573\/revisions"}],"predecessor-version":[{"id":60816,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/45573\/revisions\/60816"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=45573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=45573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=45573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}