{"id":399,"date":"2005-12-11T09:33:19","date_gmt":"2005-12-11T08:33:19","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/2005\/12\/11\/3-advent\/"},"modified":"2005-12-11T16:33:49","modified_gmt":"2005-12-11T15:33:49","slug":"3-advent","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2005\/12\/11\/3-advent\/","title":{"rendered":"3. Advent"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/themes\/diabsite\/images\/advent3.gif\" width=\"300\" height=\"57\" alt=\"Adventsgirlande\" title=\"Adventsgirlande\" \/> Sie haben die dritte Kerze im Adventskranz angez\u00fcndet? Die DiabSite-Redaktion w\u00fcnscht Ihnen einen sch\u00f6nen 3.&nbsp;Adventssonntag. Vielleicht basteln sie Strohsterne, singen Advents- und Weihnachtslieder oder besuchen Freunde zum Adventskaffee. Was immer Sie heute besch\u00e4ftigt, bitte vergessen Sie trotz des vielerorts nass-kalten Wetters einen kleinen Spaziergang und nat\u00fcrlich das elfte T\u00fcrchen im <a href=\"https:\/\/www.diabsite.de\/advent\/2005\/index.html\" target=\"_blank\">Adventskalender mit Diabetes-Quiz<\/a> auf DiabSite nicht. Wir freuen uns auf Ihren Besuch!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie haben die dritte Kerze im Adventskranz angez\u00fcndet? Die DiabSite-Redaktion w\u00fcnscht Ihnen einen sch\u00f6nen 3.&nbsp;Adventssonntag. Vielleicht basteln sie Strohsterne, singen Advents- und Weihnachtslieder oder besuchen Freunde zum Adventskaffee. Was immer Sie heute besch\u00e4ftigt, bitte vergessen Sie trotz des vielerorts nass-kalten Wetters einen kleinen Spaziergang und nat\u00fcrlich das elfte T\u00fcrchen im Adventskalender mit Diabetes-Quiz auf DiabSite [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/399"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=399"}],"version-history":[{"count":0,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/399\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}