{"id":395,"date":"2005-12-08T11:39:00","date_gmt":"2005-12-08T09:39:00","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/2005\/12\/08\/weihnachtsbackerei-mit-nahrstoffangaben-fur-diabetiker\/"},"modified":"2016-09-23T14:26:54","modified_gmt":"2016-09-23T12:26:54","slug":"weihnachtsbaeckerei-mit-naehrwertangaben-fuer-diabetiker","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2005\/12\/08\/weihnachtsbaeckerei-mit-naehrwertangaben-fuer-diabetiker\/","title":{"rendered":"Haselnuss-Pl\u00e4tzchen"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/haselnuss-plaetzchen.html\" target=\"_blank\" title=\"zum Rezept\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/themes\/diabsite\/images\/haselnuss-plaetzchen.jpg\" width=\"150\" height=\"206\" alt=\"Haselnuss-Pl\u00e4tzchen\" title=\"Haselnuss-Pl\u00e4tzchen\" \/><\/a> Weihnachten ist nicht mehr weit. Mit der Adventsb\u00e4ckerei sind wir kurz nach Nikolaus schon etwas sp\u00e4t dran. Doch nun hat uns der allerorts vorhandene Duft nach Anis, Vanille und Lebkuchengew\u00fcrz verf\u00fchrt, Ihnen einige Rezepte f\u00fcr die Advents- und Weihnachtsb\u00e4ckerei vorzustellen, die auch Diabetiker essen k\u00f6nnen. Allerdings sollten besonders \u00fcbergewichtige Typ&nbsp;2 Diabetiker auch in der Adventszeit nur in Ma\u00dfen naschen. Alle <a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/_backrezepte.html\" target=\"_blank\" title=\"zu den Backrezepten\">Backrezepte<\/a> enthalten nat\u00fcrlich N\u00e4hrwertangaben f\u00fcr die BE-Berechnung. Wir starten heute mit leckeren <a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/haselnuss-plaetzchen.html\" target=\"_blank\" title=\"zum Rezept\">Haselnuss-Pl\u00e4tzchen<\/a>, die Sie mit einer ganzen Haselnuss auf dem Pl\u00e4tzchen verzieren k\u00f6nnen. Das DiabSite-Team w\u00fcnscht Ihnen einen guten Appetit!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weihnachten ist nicht mehr weit. Mit der Adventsb\u00e4ckerei sind wir kurz nach Nikolaus schon etwas sp\u00e4t dran. Doch nun hat uns der allerorts vorhandene Duft nach Anis, Vanille und Lebkuchengew\u00fcrz verf\u00fchrt, Ihnen einige Rezepte f\u00fcr die Advents- und Weihnachtsb\u00e4ckerei vorzustellen, die auch Diabetiker essen k\u00f6nnen. Allerdings sollten besonders \u00fcbergewichtige Typ&nbsp;2 Diabetiker auch in der Adventszeit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/395"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=395"}],"version-history":[{"count":4,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/395\/revisions"}],"predecessor-version":[{"id":40457,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/395\/revisions\/40457"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}