{"id":390,"date":"2005-12-05T22:26:34","date_gmt":"2005-12-05T21:26:34","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/2005\/12\/05\/20-prozent-der-schulkinder-in-europa-haben-ubergewicht\/"},"modified":"2005-12-05T22:27:06","modified_gmt":"2005-12-05T21:27:06","slug":"20-prozent-der-schulkinder-in-europa-haben-ubergewicht","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2005\/12\/05\/20-prozent-der-schulkinder-in-europa-haben-ubergewicht\/","title":{"rendered":"20 Prozent der Schulkinder in Europa haben \u00dcbergewicht"},"content":{"rendered":"<p>Mit wachsender Besorgnis wird die Verbreitung von \u00dcbergewicht und Adipositas (Fettleibigkeit) bei Kindern beobachtet. Ungef\u00e4hr 20&nbsp;Prozent aller Kinder im schulf\u00e4higen Alter sind \u00fcbergewichtig. Das Problem tritt europaweit auf, die Weltgesundheitsorganisation&nbsp;(WHO) spricht deshalb schon von einer Epidemie. Ein Viertel der \u00fcbergewichtigen Kinder gilt als fettleibig. Damit ist f\u00fcr sie das Risiko deutlich erh\u00f6ht, noch vor Erreichen des Erwachsenenalters oder als junge Erwachsene an Herz-Kreislauf-Erkrankungen, Typ&nbsp;2 Diabetes und anderen Krankheiten zu erkranken. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2005\/051205b.html\" target=\"_blank\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit wachsender Besorgnis wird die Verbreitung von \u00dcbergewicht und Adipositas (Fettleibigkeit) bei Kindern beobachtet. Ungef\u00e4hr 20&nbsp;Prozent aller Kinder im schulf\u00e4higen Alter sind \u00fcbergewichtig. Das Problem tritt europaweit auf, die Weltgesundheitsorganisation&nbsp;(WHO) spricht deshalb schon von einer Epidemie. Ein Viertel der \u00fcbergewichtigen Kinder gilt als fettleibig. Damit ist f\u00fcr sie das Risiko deutlich erh\u00f6ht, noch vor Erreichen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/390"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":0,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/390\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}