{"id":36870,"date":"2015-11-11T12:59:02","date_gmt":"2015-11-11T11:59:02","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=36870"},"modified":"2015-11-11T21:12:10","modified_gmt":"2015-11-11T20:12:10","slug":"meeting-der-european-association-for-the-study-of-diabeteseasd","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2015\/11\/11\/meeting-der-european-association-for-the-study-of-diabeteseasd\/","title":{"rendered":"Meeting der &#8222;European Association for the Study of Diabetes&#8220;&nbsp;(EASD)"},"content":{"rendered":"<p>Deutsche Diabetesforschung in Stockholm mehrfach ausgezeichnet: Auf dem 51. Meeting der &#8222;European Association for the Study of Diabetes&#8220;&nbsp;(EASD) ist die deutsche Diabetesforschung in herausragender Weise geehrt worden. Insgesamt vier von sechs EASD-Wissenschaftspreisen gingen an deutsche Wissenschaftler. Die EASD-Tagung, die im September in Stockholm stattfand, ist mit etwa 20.000&nbsp;Besuchern der weltweit gr\u00f6\u00dfte Diabeteskongress. &#8222;Die Auszeichnungen belegen eindrucksvoll, dass die deutsche Diabetesforschung auf einem sehr guten Weg ist&#8220;, freut sich Professor Dr.&nbsp;med.&nbsp;Baptist Gallwitz, Pr\u00e4sident der Deutschen Diabetes Gesellschaft&nbsp;(DDG).  <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2015\/151111.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche Diabetesforschung in Stockholm mehrfach ausgezeichnet: Auf dem 51. Meeting der &#8222;European Association for the Study of Diabetes&#8220;&nbsp;(EASD) ist die deutsche Diabetesforschung in herausragender Weise geehrt worden. Insgesamt vier von sechs EASD-Wissenschaftspreisen gingen an deutsche Wissenschaftler. Die EASD-Tagung, die im September in Stockholm stattfand, ist mit etwa 20.000&nbsp;Besuchern der weltweit gr\u00f6\u00dfte Diabeteskongress. &#8222;Die Auszeichnungen belegen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[5547,24,1012,177,5081,5546],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/36870"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=36870"}],"version-history":[{"count":3,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/36870\/revisions"}],"predecessor-version":[{"id":36873,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/36870\/revisions\/36873"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=36870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=36870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=36870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}