{"id":35939,"date":"2015-08-24T18:09:51","date_gmt":"2015-08-24T16:09:51","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=35939"},"modified":"2015-08-25T21:52:58","modified_gmt":"2015-08-25T19:52:58","slug":"bestnoten-fuer-aerzte-im-herz-und-diabeteszentrum-nrw","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2015\/08\/24\/bestnoten-fuer-aerzte-im-herz-und-diabeteszentrum-nrw\/","title":{"rendered":"Bestnoten f\u00fcr \u00c4rzte im Herz- und Diabeteszentrum NRW"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2015\/150824b.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2015\/150824b.jpg\" width=\"150\" height=\"84\" alt=\"Gesch\u00e4ftsf\u00fchrerin Dr. Karin Overlack (Mitte) gratuliert den f\u00fcnf HDZ-Spezialisten zu ihrer Auszeichnung\"\/><\/a> Auch in diesem Jahr d\u00fcrfen sich wieder f\u00fcnf Mediziner aus dem Herz- und Diabeteszentrum&nbsp;NRW zu den besten Fach\u00e4rzten z\u00e4hlen, die das Nachrichtenmagazin Focus in Deutschlands gr\u00f6\u00dfter \u00c4rztebewertung ermittelt hat. Hervorragende Leistungen in Pr\u00e4vention, Diagnostik und Therapie werden den Herzspezialisten Prof.&nbsp;Dr.&nbsp;Dieter Horstkotte, Prof.&nbsp;Dr.&nbsp;Jan Gummert und Dr.&nbsp;Siegfried Eckert sowie dem Leiter des Departments f\u00fcr Fetale Kardiologie am HDZ-Kinderherzzentrum, Dr.&nbsp;Johannes Steinhard, ebenso wie dem Chefarzt der Diabetologie, Prof.&nbsp;Dr.&nbsp;Dr.&nbsp;h.c.&nbsp;Diethelm Tsch\u00f6pe, bescheinigt. Prof.&nbsp;Tsch\u00f6pe wird dabei zum zweiten Mal in Folge als bundesweit bester Spezialist zur Behandlung von Diabeteserkrankungen ausgezeichnet. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2015\/150824b.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch in diesem Jahr d\u00fcrfen sich wieder f\u00fcnf Mediziner aus dem Herz- und Diabeteszentrum&nbsp;NRW zu den besten Fach\u00e4rzten z\u00e4hlen, die das Nachrichtenmagazin Focus in Deutschlands gr\u00f6\u00dfter \u00c4rztebewertung ermittelt hat. Hervorragende Leistungen in Pr\u00e4vention, Diagnostik und Therapie werden den Herzspezialisten Prof.&nbsp;Dr.&nbsp;Dieter Horstkotte, Prof.&nbsp;Dr.&nbsp;Jan Gummert und Dr.&nbsp;Siegfried Eckert sowie dem Leiter des Departments f\u00fcr Fetale Kardiologie am [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[24,5284,5283,5282,444],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/35939"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=35939"}],"version-history":[{"count":5,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/35939\/revisions"}],"predecessor-version":[{"id":35945,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/35939\/revisions\/35945"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=35939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=35939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=35939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}