{"id":35857,"date":"2015-08-20T16:09:03","date_gmt":"2015-08-20T14:09:03","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=35857"},"modified":"2015-08-20T19:20:49","modified_gmt":"2015-08-20T17:20:49","slug":"neuer-diabetestyp-nach-partieller-pankreatektomie-reversibel","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2015\/08\/20\/neuer-diabetestyp-nach-partieller-pankreatektomie-reversibel\/","title":{"rendered":"Neuer Diabetestyp nach partieller Pankreatektomie reversibel"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2015\/150820.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2015\/150820.jpg\" width=\"150\" height=\"117\" alt=\"Dr. Florian Ehehalt und Prof. Michele Solimena\" \/><\/a> Welche Patienten k\u00f6nnen hinsichtlich einer Verbesserung des Diabetes profitieren? Erstmals wurde genauer spezifiziert, bei welchen Patienten mit Pankreastumoren, die eine Hyperglyk\u00e4mie und Diabetes entwickeln, sich nach partieller Pankreatektomie auch die Blutzucker-Hom\u00f6ostase verbessert. Die Ergebnisse k\u00f6nnen \u00c4rzte dabei unterst\u00fctzen, die postoperativen Konsequenzen einer Pankreas-Resektion genauer einzusch\u00e4tzen. Die Untersuchung wurde geleitet von Dr.&nbsp;Ehehalt, Prof.&nbsp;Solimena und Prof.&nbsp;Gr\u00fctzmann aus der Chirurgie des Universit\u00e4tsklinikums Carl Gustav Carus und des Paul Langerhans Instituts Dresden des Helmholtz Zentrums M\u00fcnchen am Universit\u00e4tsklinikum Carl Gustav Carus der TU&nbsp;Dresden, die unter dem Dach des Deutschen Zentrums f\u00fcr Diabetesforschung&nbsp;(DZD) kooperieren. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2015\/150820.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welche Patienten k\u00f6nnen hinsichtlich einer Verbesserung des Diabetes profitieren? Erstmals wurde genauer spezifiziert, bei welchen Patienten mit Pankreastumoren, die eine Hyperglyk\u00e4mie und Diabetes entwickeln, sich nach partieller Pankreatektomie auch die Blutzucker-Hom\u00f6ostase verbessert. Die Ergebnisse k\u00f6nnen \u00c4rzte dabei unterst\u00fctzen, die postoperativen Konsequenzen einer Pankreas-Resektion genauer einzusch\u00e4tzen. Die Untersuchung wurde geleitet von Dr.&nbsp;Ehehalt, Prof.&nbsp;Solimena und Prof.&nbsp;Gr\u00fctzmann aus [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[24,5268,5267,5264,5266,5265],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/35857"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=35857"}],"version-history":[{"count":3,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/35857\/revisions"}],"predecessor-version":[{"id":35861,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/35857\/revisions\/35861"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=35857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=35857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=35857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}