{"id":343,"date":"2005-11-10T11:07:16","date_gmt":"2005-11-10T10:07:16","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/2005\/11\/13\/studie-zu-gesundheitssystemen-trend-in-eu-landern-geht-zu-starkerer-steuerfinanzierung\/"},"modified":"2005-11-13T21:17:13","modified_gmt":"2005-11-13T20:17:13","slug":"studie-zu-gesundheitssystemen-trend-in-eu-landern-geht-zu-starkerer-steuerfinanzierung","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2005\/11\/10\/studie-zu-gesundheitssystemen-trend-in-eu-landern-geht-zu-starkerer-steuerfinanzierung\/","title":{"rendered":"Studie zu Gesundheitssystemen: Trend in EU-L\u00e4ndern geht zu st\u00e4rkerer Steuerfinanzierung"},"content":{"rendered":"<p>Deutschlands Nachbarl\u00e4nder finanzieren ihre Gesundheitssysteme zunehmend aus Steuermitteln. In Luxemburg, \u00d6sterreich oder Belgien erg\u00e4nzen Steuertransfers mittlerweile in wesentlichem Umfang das traditionelle Krankenversicherungssystem auf der Basis einkommensabh\u00e4ngiger Beitr\u00e4ge. Doch steuerfinanzierte Gesundheitssysteme sind nach Ansicht von Forschern h\u00e4ufig unterfinanziert. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/gesundheitspolitik\/news\/2005\/051110b.html\" target=\"_blank\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschlands Nachbarl\u00e4nder finanzieren ihre Gesundheitssysteme zunehmend aus Steuermitteln. In Luxemburg, \u00d6sterreich oder Belgien erg\u00e4nzen Steuertransfers mittlerweile in wesentlichem Umfang das traditionelle Krankenversicherungssystem auf der Basis einkommensabh\u00e4ngiger Beitr\u00e4ge. Doch steuerfinanzierte Gesundheitssysteme sind nach Ansicht von Forschern h\u00e4ufig unterfinanziert. Nachricht lesen<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/343"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=343"}],"version-history":[{"count":0,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/343\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}