{"id":328,"date":"2005-11-11T14:46:33","date_gmt":"2005-11-11T13:46:33","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/2005\/11\/11\/lesetipps-auch-fur-diabetes-experten\/"},"modified":"2005-11-11T14:46:58","modified_gmt":"2005-11-11T13:46:58","slug":"lesetipps-auch-fur-diabetes-experten","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2005\/11\/11\/lesetipps-auch-fur-diabetes-experten\/","title":{"rendered":"Lesetipps auch f\u00fcr Diabetes-Experten"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/themes\/diabsite\/images\/diabetesforum.jpg\" width=\"90\" height=\"120\" alt=\"Titelbild: Diabetesforum\" title=\"Titelbild: Diabetesforum\" \/> DiabSite stellt gedruckte Diabetes-Informationen f\u00fcr Diabetiker, aber auch Diabetes-Experten vor. So finden Sie unter <a href=\"https:\/\/www.diabsite.de\/wegweiser\/lesen\/fachzeitschriften.html\" target=\"_blank\">Fachzeitschriften<\/a> zum Beispiel das &#8222;Diabetesforum&#8220;, das monatlich erscheint und sich als Forum f\u00fcr die professionelle Diabetiker-Versorgung vor allem an Diabetesberater und Di\u00e4tassistenten wendet. Weitere Empfehlungen zu B\u00fcchern und Zeitschriften sowie einige Kundenmagazine zum direkten Download finden Sie in unseren <a href=\"https:\/\/www.diabsite.de\/wegweiser\/lesen\/index.html\" target=\"_blank\">Lesetipps<\/a>. Wir w\u00fcnschen Ihnen wie immer eine interessante Lekt\u00fcre!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DiabSite stellt gedruckte Diabetes-Informationen f\u00fcr Diabetiker, aber auch Diabetes-Experten vor. So finden Sie unter Fachzeitschriften zum Beispiel das &#8222;Diabetesforum&#8220;, das monatlich erscheint und sich als Forum f\u00fcr die professionelle Diabetiker-Versorgung vor allem an Diabetesberater und Di\u00e4tassistenten wendet. Weitere Empfehlungen zu B\u00fcchern und Zeitschriften sowie einige Kundenmagazine zum direkten Download finden Sie in unseren Lesetipps. Wir [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/328"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=328"}],"version-history":[{"count":0,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/328\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}