{"id":32173,"date":"2014-10-10T15:50:13","date_gmt":"2014-10-10T13:50:13","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=32173"},"modified":"2014-10-11T21:24:10","modified_gmt":"2014-10-11T19:24:10","slug":"erfolge-bei-diabetes-folgeerkrankungen-versagen-bei-primarpravention","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2014\/10\/10\/erfolge-bei-diabetes-folgeerkrankungen-versagen-bei-primarpravention\/","title":{"rendered":"Erfolge bei Diabetes-Folgeerkrankungen, Versagen bei Prim\u00e4rpr\u00e4vention"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2014\/141010.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2014\/141010-siegel.jpg\" width=\"120\" height=\"160\" alt=\"PD Dr. med. Erhard Siegel\" \/><\/a> Vor 25 Jahren trafen sich Vertreter von Gesundheitsministerien und Patientenorganisationen aus Europa und berieten mit Experten \u00fcber die zunehmende Diabetesepidemie. Auf Initiative der Weltgesundheitsorganisation&nbsp;(WHO) und der Internationalen Diabetesf\u00f6deration&nbsp;(IDF) wurden die Staaten aufgefordert, Pl\u00e4ne zur Verh\u00fctung, Erkennung und Behandlung des Diabetes zu erarbeiten. Besonders sollten die gravierenden Folgeerkrankungen des Diabetes wie Blindheit, Nierensch\u00e4den und Amputationen reduziert und die zunehmende Diabetesepidemie gestoppt werden. Dazu bilanziert die Deutsche Diabetes Gesellschaft: &#8222;Erfolgen bei der Bek\u00e4mpfung der Folgeerkrankungen des Diabetes steht ein klares Versagen in der Prim\u00e4rpr\u00e4vention gegen\u00fcber.&#8220; <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2014\/141010.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor 25 Jahren trafen sich Vertreter von Gesundheitsministerien und Patientenorganisationen aus Europa und berieten mit Experten \u00fcber die zunehmende Diabetesepidemie. Auf Initiative der Weltgesundheitsorganisation&nbsp;(WHO) und der Internationalen Diabetesf\u00f6deration&nbsp;(IDF) wurden die Staaten aufgefordert, Pl\u00e4ne zur Verh\u00fctung, Erkennung und Behandlung des Diabetes zu erarbeiten. Besonders sollten die gravierenden Folgeerkrankungen des Diabetes wie Blindheit, Nierensch\u00e4den und Amputationen reduziert [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[817,4240,4241,92],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/32173"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=32173"}],"version-history":[{"count":7,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/32173\/revisions"}],"predecessor-version":[{"id":32187,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/32173\/revisions\/32187"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=32173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=32173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=32173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}