{"id":29670,"date":"2014-03-24T14:07:49","date_gmt":"2014-03-24T13:07:49","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=29670"},"modified":"2014-03-24T21:59:35","modified_gmt":"2014-03-24T20:59:35","slug":"diabetes-thema-einer-neuen-forschungskooperation","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2014\/03\/24\/diabetes-thema-einer-neuen-forschungskooperation\/","title":{"rendered":"Diabetes &#8211; Thema einer neuen Forschungskooperation"},"content":{"rendered":"<p>Sanofi, die Ludwig-Maximilians-Universit\u00e4t (LMU) und das Klinikum der Universit\u00e4t M\u00fcnchen haben vereinbart, k\u00fcnftig in der medizinischen Forschung und bei der Entwicklung neuer Therapien als strategische Partner zusammenzuarbeiten. Ein ent\u00adsprechender Rahmenvertrag \u00fcber eine Laufzeit von zun\u00e4chst drei Jahren wurde jetzt unterzeichnet. Im Fokus stehen einerseits Erkrankungen wie etwa Diabetes, Multiple Sklerose oder Infektions\u00adkrankheiten, andererseits translationale Technologien und Modelle, die es erlauben sollen, besser als bisher zu \u00fcberpr\u00fcfen, inwieweit neue therapeutische Ans\u00e4tze aus dem Labor in die Klinik \u00fcbertragbar sind. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2014\/140324.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sanofi, die Ludwig-Maximilians-Universit\u00e4t (LMU) und das Klinikum der Universit\u00e4t M\u00fcnchen haben vereinbart, k\u00fcnftig in der medizinischen Forschung und bei der Entwicklung neuer Therapien als strategische Partner zusammenzuarbeiten. Ein ent\u00adsprechender Rahmenvertrag \u00fcber eine Laufzeit von zun\u00e4chst drei Jahren wurde jetzt unterzeichnet. Im Fokus stehen einerseits Erkrankungen wie etwa Diabetes, Multiple Sklerose oder Infektions\u00adkrankheiten, andererseits translationale Technologien [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[24,973,3446,3445,92],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/29670"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=29670"}],"version-history":[{"count":4,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/29670\/revisions"}],"predecessor-version":[{"id":29687,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/29670\/revisions\/29687"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=29670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=29670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=29670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}