{"id":17138,"date":"2012-01-23T15:15:14","date_gmt":"2012-01-23T14:15:14","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=17138"},"modified":"2012-01-23T15:15:14","modified_gmt":"2012-01-23T14:15:14","slug":"bodensee-freizeit-2012-fur-kinder-mit-typ-1-diabetes","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2012\/01\/23\/bodensee-freizeit-2012-fur-kinder-mit-typ-1-diabetes\/","title":{"rendered":"Bodensee-Freizeit 2012 f\u00fcr Kinder mit Typ-1-Diabetes"},"content":{"rendered":"<p>Kinder und Jugendliche mit Diabetes stehen t\u00e4glich vor allt\u00e4glichen Herausforderungen: Sie m\u00fcssen stets den optimalen Weg zwischen Disziplin und Verantwortungsbewusstsein in der Therapie und dem Bed\u00fcrfnis nach Spiel und Spa\u00df finden. Um diese H\u00fcrden spielerisch zu nehmen, bietet diabetesDE&nbsp;\u2013 Deutsche Diabetes-Hilfe dieses Jahr gemeinsam mit dem Diabetes Forum Radolfzell eine Freizeit f\u00fcr Kinder und Jugendliche mit Diabetes in S\u00fcddeutschland an. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2012\/120123b.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kinder und Jugendliche mit Diabetes stehen t\u00e4glich vor allt\u00e4glichen Herausforderungen: Sie m\u00fcssen stets den optimalen Weg zwischen Disziplin und Verantwortungsbewusstsein in der Therapie und dem Bed\u00fcrfnis nach Spiel und Spa\u00df finden. Um diese H\u00fcrden spielerisch zu nehmen, bietet diabetesDE&nbsp;\u2013 Deutsche Diabetes-Hilfe dieses Jahr gemeinsam mit dem Diabetes Forum Radolfzell eine Freizeit f\u00fcr Kinder und Jugendliche [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/17138"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=17138"}],"version-history":[{"count":5,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/17138\/revisions"}],"predecessor-version":[{"id":17143,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/17138\/revisions\/17143"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=17138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=17138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=17138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}