{"id":11961,"date":"2011-01-01T21:16:51","date_gmt":"2011-01-01T20:16:51","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=11961"},"modified":"2011-03-09T22:26:36","modified_gmt":"2011-03-09T21:26:36","slug":"schritte-zahlen-ein-guter-vorsazu-fur-2011","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2011\/01\/01\/schritte-zahlen-ein-guter-vorsazu-fur-2011\/","title":{"rendered":"Schritte z\u00e4hlen &#8211; ein guter Vorsatz f\u00fcr 2011"},"content":{"rendered":"<p>Gewiss sind auch Sie mit vielen guten Vors\u00e4tzen ins neue Jahr gestartet. Was immer Sie sich f\u00fcr 2011 vorgenommen haben, eine ges\u00fcndere Ern\u00e4hrung und mehr Bewegung sollten auf der Liste nicht fehlen. Diese beiden S\u00e4ulen eines gesunden Lebensstils sind der beste Schutz vor vielen Krankheiten. <\/p>\n<p>Wie eine gesunde Ern\u00e4hrung aussieht, wei\u00df heute jeder, aber was hei\u00dft mehr Bewegung? Nein, Sie m\u00fcssen nicht t\u00e4glich ins Fitnessstudio. Experten versichern, dass 30 Minuten moderate k\u00f6rperliche Aktivit\u00e4t, zum Beispiel z\u00fcgiges Spazierengehen, an mindestens 5 Tagen in der Woche ausreichen, um einem Diabetes Typ 2 vorzubeugen. Aber auch Typ-2-Diabetiker profitieren von Bewegung. Sie verbessert Blutzuckereinstellung, Blutdruck und Blutfettwerte.<\/p>\n<p>Mein Tipp aus eigener Erfahrung: Langsam anfangen und den inneren Schweinehund mit Motivationshilfen bek\u00e4mpfen! G\u00f6nnen Sie sich einen Schrittz\u00e4hler oder dokumentieren Sie Ihre k\u00f6rperlichen Aktivit\u00e4ten in Minuten. Dann k\u00f6nnen Sie sich \u00fcber zus\u00e4tzliche Schritte oder Minuten in Ihrem pers\u00f6nlichen Bewegungsprotokoll freuen.<\/p>\n<p>Achtung! Diabetiker, die mit Sulfonylharnstoffen, Gliniden oder Insulin behandelt werden, sollten vor, w\u00e4hrend und nach der k\u00f6rperlichen Bewegung h\u00e4ufiger ihren Blutzucker messen. Bitte sprechen Sie mir Ihrem Arzt dar\u00fcber.<\/p>\n<p>Ich w\u00fcnsche Ihnen viel Gesundheit f\u00fcr 2011!<br \/> <br \/>\nIhre Helga Uphoff<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gewiss sind auch Sie mit vielen guten Vors\u00e4tzen ins neue Jahr gestartet. Was immer Sie sich f\u00fcr 2011 vorgenommen haben, eine ges\u00fcndere Ern\u00e4hrung und mehr Bewegung sollten auf der Liste nicht fehlen. Diese beiden S\u00e4ulen eines gesunden Lebensstils sind der beste Schutz vor vielen Krankheiten. Wie eine gesunde Ern\u00e4hrung aussieht, wei\u00df heute jeder, aber was [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11961"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=11961"}],"version-history":[{"count":9,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11961\/revisions"}],"predecessor-version":[{"id":12630,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11961\/revisions\/12630"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=11961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=11961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=11961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}