{"id":11777,"date":"2010-12-19T12:57:57","date_gmt":"2010-12-19T11:57:57","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=11777"},"modified":"2012-03-16T14:41:04","modified_gmt":"2012-03-16T13:41:04","slug":"gefuellte-gaensekeulen-mit-nudeln","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2010\/12\/19\/gefuellte-gaensekeulen-mit-nudeln\/","title":{"rendered":"Gef\u00fcllte G\u00e4nsekeulen mit Nudeln"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/gefuellte-gaensekeulen.html\" target=\"_blank\" class=\"ds\" title=\"Rezept (neues Fenster)\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2010\/gefuellte-gaensekeulen.jpg\" width=\"150\" height=\"210\" alt=\"Rezeptfoto\" \/><\/a> Weihnachten steht vor der T\u00fcr. Und was w\u00e4re das Fest ohne eine Weihnachtsgans? Aber wer nicht gerade eine 5-k\u00f6pfige Familie zu verk\u00f6stigen hat, f\u00fcr den ist eine ganze Gans oft eine Nummer zu gro\u00df. Mit unserem heutigen Rezeptvorschlag: <a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/gefuellte-gaensekeulen.html\" target=\"_blank\" class=\"ds\" title=\"Rezept (neues Fenster)\">Gef\u00fcllte G\u00e4nsekeulen mit Nudeln<\/a> m\u00fcssen auch Kleinfamilien und Singles zu Weihnachten nicht auf den Geschmack ihres Lieblingsgerichts verzichten. Die Keulen werden mit Zucchini, M\u00f6hren und Tomaten gef\u00fcllt und m\u00fcssen nur etwa 30&nbsp;Minuten im Ofen schmoren. Dazu gibt es neben einer leckeren Rotwein-Sauce schnell gekochte Bandnudeln. Weitere <a href=\"https:\/\/www.diabsite.de\/ernaehrung\/rezepte\/index.html\" target=\"_blank\" class=\"ds\" title=\"neues Fenster\">Rezepte<\/a> f\u00fcr jede Gelegenheit finden Sie auf dem Diabetes-Portal DiabSite. Wir w\u00fcnschen Ihnen einen sch\u00f6nen 4.&nbsp;Advent und guten Appetit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weihnachten steht vor der T\u00fcr. Und was w\u00e4re das Fest ohne eine Weihnachtsgans? Aber wer nicht gerade eine 5-k\u00f6pfige Familie zu verk\u00f6stigen hat, f\u00fcr den ist eine ganze Gans oft eine Nummer zu gro\u00df. Mit unserem heutigen Rezeptvorschlag: Gef\u00fcllte G\u00e4nsekeulen mit Nudeln m\u00fcssen auch Kleinfamilien und Singles zu Weihnachten nicht auf den Geschmack ihres Lieblingsgerichts [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11777"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=11777"}],"version-history":[{"count":12,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11777\/revisions"}],"predecessor-version":[{"id":18000,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11777\/revisions\/18000"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=11777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=11777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=11777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}