{"id":11676,"date":"2010-11-11T21:36:58","date_gmt":"2010-11-11T20:36:58","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=11676"},"modified":"2010-12-09T19:19:26","modified_gmt":"2010-12-09T18:19:26","slug":"ab-2011-werden-patienten-unabhangig-beraten","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2010\/11\/11\/ab-2011-werden-patienten-unabhangig-beraten\/","title":{"rendered":"Ab 2011 werden Patienten unabh\u00e4ngig beraten"},"content":{"rendered":"<p>Der Deutsche Bundestag beschlie\u00dft heute mit dem &#8218;Gesetz zur Neuordnung des Arzneimittelmarktes in der gesetzlichen Krankenversicherung&nbsp;&#8211; AMNOG&#8216; auch die Einrichtungen der unabh\u00e4ngigen Patientenberatung. Dazu erkl\u00e4rt der Patientenbeauftragte der Bundesregierung, Wolfgang Z\u00f6ller&nbsp;(MdB): &#8222;Mit der unabh\u00e4ngigen Patientenberatung erhalten Patienten und Versicherten verl\u00e4ssliche Informations- und Beratungsangebote, damit sie ihre Rechte besser durchsetzen k\u00f6nnen. <a href=\"https:\/\/www.diabsite.de\/aktuelles\/nachrichten\/2010\/101111c.html\" target=\"_blank\" class=\"ds\" title=\"zur Nachricht (neues Fenster)\">Nachricht lesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Deutsche Bundestag beschlie\u00dft heute mit dem &#8218;Gesetz zur Neuordnung des Arzneimittelmarktes in der gesetzlichen Krankenversicherung&nbsp;&#8211; AMNOG&#8216; auch die Einrichtungen der unabh\u00e4ngigen Patientenberatung. Dazu erkl\u00e4rt der Patientenbeauftragte der Bundesregierung, Wolfgang Z\u00f6ller&nbsp;(MdB): &#8222;Mit der unabh\u00e4ngigen Patientenberatung erhalten Patienten und Versicherten verl\u00e4ssliche Informations- und Beratungsangebote, damit sie ihre Rechte besser durchsetzen k\u00f6nnen. Nachricht lesen<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11676"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=11676"}],"version-history":[{"count":2,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11676\/revisions"}],"predecessor-version":[{"id":11678,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11676\/revisions\/11678"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=11676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=11676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=11676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}