{"id":11332,"date":"2010-11-11T20:36:18","date_gmt":"2010-11-11T19:36:18","guid":{"rendered":"http:\/\/www.diabsite.de\/diabetes-weblog\/?p=11332"},"modified":"2010-11-11T21:27:10","modified_gmt":"2010-11-11T20:27:10","slug":"vdbd-zusammenarbeit-mit-diabetesde-ja-aber-anders","status":"publish","type":"post","link":"https:\/\/www.diabsite.de\/diabetes-weblog\/2010\/11\/11\/vdbd-zusammenarbeit-mit-diabetesde-ja-aber-anders\/","title":{"rendered":"VDBD: Zusammenarbeit mit diabetesDE ja &#8211; aber anders"},"content":{"rendered":"<p><a href=\"https:\/\/www.diabetes-radio.de\/\" target=\"_blank\" class=\"radio\" title=\"zum DiabSite Diabetes-Radio (neues Fenster)\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/themes\/diabsite\/images\/diabetes-radio.gif\" width=\"100\" height=\"100\" alt=\"Logo vom DiabSite Diabetes-Radio\" \/><\/a> Seit vielen Jahren gibt es Bestrebungen, die einzelnen Organisationen im Bereich Diabetes zu einen. Dies ist auch das oberste Ziel von diabetesDE. Nach dem Vorbild von diabetesUK w\u00fcrde man gerne&nbsp;&#8211; vor allem gegen\u00fcber der Politik&nbsp;&#8211; mit einer Stimme sprechen. Bis heute ist dieses Ziel jedoch nicht erreicht. Wie geht es weiter? Diese Frage stellte sich im Vorfeld der 4.&nbsp;Herbsttagung der Deutschen Diabetes-Gesellschaft auch der Verband der Diabetes-Beratungs- und Schulungsberufe in Deutschland (VDBD). <a href=\"https:\/\/www.diabetes-radio.de\/2010\/11\/05\/\" target=\"_blank\" class=\"radio\" title=\"neues Fenster\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-content\/images\/2010\/101105-drobinski.jpg\" width=\"120\" height=\"160\" alt=\"Evelyn Drobinski\" \/><\/a> So lud der VDBD-Vorstand Anfang November zu einer au\u00dferordentlichen Mitgliederversammlung ein, um \u00fcber den k\u00fcnftigen gemeinsamen Weg mit diabetesDe zu diskutieren. Mit Evelyn Drobinski, Diabetesberaterin und ehrenamtliche VDBD-Vorsitzende, sprach DiabSite-Redakteurin Helga Uphoff \u00fcber Aufgaben und Interessen des Verbands sowie \u00fcber das mit Spannung erwartete Mitglieder-Votum. Das Interview steht ab sofort ebenfalls im <a href=\"https:\/\/www.diabetes-radio.de\/2010\/11\/05\/\" target=\"_blank\" class=\"radio\" title=\"neues Fenster\">DiabSite Diabetes-Radio <\/a> zum Anh\u00f6ren bereit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit vielen Jahren gibt es Bestrebungen, die einzelnen Organisationen im Bereich Diabetes zu einen. Dies ist auch das oberste Ziel von diabetesDE. Nach dem Vorbild von diabetesUK w\u00fcrde man gerne&nbsp;&#8211; vor allem gegen\u00fcber der Politik&nbsp;&#8211; mit einer Stimme sprechen. Bis heute ist dieses Ziel jedoch nicht erreicht. Wie geht es weiter? Diese Frage stellte sich [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11332"}],"collection":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/comments?post=11332"}],"version-history":[{"count":5,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11332\/revisions"}],"predecessor-version":[{"id":11338,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/posts\/11332\/revisions\/11338"}],"wp:attachment":[{"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/media?parent=11332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/categories?post=11332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diabsite.de\/diabetes-weblog\/wp-json\/wp\/v2\/tags?post=11332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}